{"id":3039,"date":"2023-04-17T13:39:01","date_gmt":"2023-04-17T11:39:01","guid":{"rendered":"http:\/\/3.72.156.28\/es\/blog\/?p=3039"},"modified":"2025-05-13T16:04:02","modified_gmt":"2025-05-13T14:04:02","slug":"case-study-of-rgb-idea-group","status":"publish","type":"post","link":"\/es\/blog\/case-study-of-rgb-idea-group.html","title":{"rendered":"Estrategia eficaz de cobertura medi\u00e1tica de una agencia de marcas y eventos. Caso pr\u00e1ctico de RGB Idea Group"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\">En PRNEWS.IO nos encanta hablar de nuestros clientes y compartir sus historias y logros. Muy a menudo nosotros mismos nos inspiramos en su ejemplo. Hoy hablamos de un cliente tan impresionante.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abCreamos marcas, eventos y contenidos con los que se sue\u00f1a y de los que se habla\u00bb.<\/p>\n<cite>Tetyana Bogoslavska-Orel, cofundadora y directora creativa de la agencia RGB IDEA GROUP.<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La agencia creativa de marcas y eventos <a href=\"https:\/\/www.rgbideagroup.com\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">RGB IDEA GROUP<\/a> es un ejemplo de marca brillante, interesante y, al mismo tiempo, muy concienciada. La agencia tiene ra\u00edces ucranianas, al igual que PRNEWS.IO, y adopta una posici\u00f3n c\u00edvica y de voluntariado muy clara. Por eso, la conversaci\u00f3n de hoy es doblemente agradable para nosotros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos que tambi\u00e9n sea de su agrado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agradecemos sinceramente a Tetyana Bogoslavska-Orel, cofundadora y directora creativa de la agencia RGB IDEA GROUP, que nos haya concedido una entrevista tan interesante y fruct\u00edfera.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/3.72.156.28\/es\/blog\/wp-content\/uploads\/2023\/04\/2-1-1024x682.png\" alt=\"Tetyana Bogoslavska-Orel, cofundadora y directora creativa de la agencia RGB IDEA GROUP.\" class=\"wp-image-3041\" srcset=\"\/es\/blog\/wp-content\/uploads\/2023\/04\/2-1-1024x682.png 1024w, \/es\/blog\/wp-content\/uploads\/2023\/04\/2-1-221x147.png 221w, \/es\/blog\/wp-content\/uploads\/2023\/04\/2-1-150x100.png 150w, \/es\/blog\/wp-content\/uploads\/2023\/04\/2-1-768x512.png 768w, \/es\/blog\/wp-content\/uploads\/2023\/04\/2-1-720x480.png 720w, \/es\/blog\/wp-content\/uploads\/2023\/04\/2-1-480x320.png 480w, \/es\/blog\/wp-content\/uploads\/2023\/04\/2-1.png 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Acerca de RGB IDEA GROUP<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La agencia RGB IDEA GROUP tiene dos oficinas: en Dnipro (Ucrania) y Fort Lauderdale (Florida, EE UU).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abSomos l\u00edderes en el sector de los eventos y estamos especializados en la promoci\u00f3n de marcas mediante la creaci\u00f3n de contenidos y estrategias \u00fanicas para llegar a cualquier mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con m\u00e1s de 10 a\u00f1os de experiencia, hemos creado contenidos de alta calidad para marcas que muestran su individualidad y singularidad. Nos entusiasma ayudar a llevar su marca al mercado internacional o local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la \u00faltima d\u00e9cada, hemos organizado eventos y actividades conceptuales para marcas de renombre como TWINSET Milano, Brunello Cucinelli y Balmain\u00bb.<\/p>\n<cite>Tetyana Bogoslavska-Orel, cofundadora y directora creativa de la agencia RGB IDEA GROUP.<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el inicio del ataque a gran escala de Rusia contra Ucrania, la cofundadora de la agencia Anastasiya Logutenko junto con Yerak Anastasiya, director ejecutivo, organizaron <a href=\"https:\/\/www.peremoga-ukraine.org\/en\/home\" target=\"_blank\" rel=\"noopener nofollow\" title=\"https:\/\/www.peremoga-ukraine.org\/en\/home\">el fondo ben\u00e9fico PEREMOGA<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Junto con el fondo PEREMOGA, el equipo de RGB IDEA GROUP coopera con UKRZALIZNYTSEA. Crearon <a href=\"https:\/\/www.rgbideagroup.com\/project\/uz-griiemo-mriiemo\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">el proyecto GRIEMO.MRIYEMO<\/a> \u2014 puntos de calefacci\u00f3n en las estaciones centrales del pa\u00eds para las personas que sufrieron la agresi\u00f3n rusa. Se trata de puntos irrompibles en el territorio del ferrocarril ucraniano \u00abUkrzaliznytsia\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"510\" src=\"https:\/\/3.72.156.28\/es\/blog\/wp-content\/uploads\/2023\/04\/3-1.png\" alt=\"el proyecto GRIEMO.MRIYEMO - puntos de calefacci\u00f3n en las estaciones centrales del pa\u00eds para las personas que sufrieron la agresi\u00f3n rusa.\" class=\"wp-image-3042\" srcset=\"\/es\/blog\/wp-content\/uploads\/2023\/04\/3-1.png 800w, \/es\/blog\/wp-content\/uploads\/2023\/04\/3-1-231x147.png 231w, \/es\/blog\/wp-content\/uploads\/2023\/04\/3-1-150x96.png 150w, \/es\/blog\/wp-content\/uploads\/2023\/04\/3-1-768x490.png 768w, \/es\/blog\/wp-content\/uploads\/2023\/04\/3-1-480x306.png 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Otro gran proyecto es <a href=\"https:\/\/www.rgbideagroup.com\/project\/light-for-ukraine\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">LUZ para Ucrania<\/a>. La empresa de medios de comunicaci\u00f3n \u00ab\u00bfPor qu\u00e9 has tardado tanto?\u00bb, el ferrocarril ucraniano \u00abUkrzaliznytsia\u00bb y la fundaci\u00f3n ben\u00e9fica ucraniana \u00abPeremoga\u00bb unieron sus fuerzas para \u00abIluminar Ucrania\u00bb con velas. Lo han hecho:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>25.000 velas de larga duraci\u00f3n<\/li>\n\n\n\n<li>un concierto en la estaci\u00f3n central para apoyar y lanzar este proyecto<\/li>\n\n\n\n<li>se recaudaron 43.831 euros para la puesta en marcha del proyecto en Kickstarter<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"510\" src=\"https:\/\/3.72.156.28\/es\/blog\/wp-content\/uploads\/2023\/04\/4.png\" alt=\"Otro gran proyecto es LIGHT for Ukraine. \" class=\"wp-image-3043\" srcset=\"\/es\/blog\/wp-content\/uploads\/2023\/04\/4.png 800w, \/es\/blog\/wp-content\/uploads\/2023\/04\/4-231x147.png 231w, \/es\/blog\/wp-content\/uploads\/2023\/04\/4-150x96.png 150w, \/es\/blog\/wp-content\/uploads\/2023\/04\/4-768x490.png 768w, \/es\/blog\/wp-content\/uploads\/2023\/04\/4-480x306.png 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la Fundaci\u00f3n PEREMOGA, junto con RGB IDEA GROUP, organiz\u00f3 una serie de <a href=\"https:\/\/officiel-online.com\/uk\/sobytiya\/ukranian-fund-peremoga-charity-dinner\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">cenas gastron\u00f3micas POIEDNANI<\/a>. Celebraron una velada gastro con chefs ucranianos y recaudaron 2 millones de jrivnias para abrir un restaurante social para desplazados en Dnipro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"972\" height=\"648\" src=\"https:\/\/3.72.156.28\/es\/blog\/wp-content\/uploads\/2023\/04\/5.png\" alt=\"La agencia RGB IDEA GROUP ya ha conseguido celebrar una velada gastron\u00f3mica con chefs ucranianos y recaudar 2 millones de jrivnias para la apertura de un restaurante social para desplazados en Dnipro.\" class=\"wp-image-3044\" srcset=\"\/es\/blog\/wp-content\/uploads\/2023\/04\/5.png 972w, \/es\/blog\/wp-content\/uploads\/2023\/04\/5-221x147.png 221w, \/es\/blog\/wp-content\/uploads\/2023\/04\/5-150x100.png 150w, \/es\/blog\/wp-content\/uploads\/2023\/04\/5-768x512.png 768w, \/es\/blog\/wp-content\/uploads\/2023\/04\/5-720x480.png 720w, \/es\/blog\/wp-content\/uploads\/2023\/04\/5-480x320.png 480w\" sizes=\"(max-width: 972px) 100vw, 972px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Impresionante, \u00bfverdad?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPor qu\u00e9 RGB IDEA GROUP solicit\u00f3 los servicios de PRNEWS.IO?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las publicaciones en los medios de comunicaci\u00f3n pueden ser una de las herramientas m\u00e1s eficaces para promocionar marcas y eventos. Pueden utilizarse para<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aumentar la visibilidad.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atraer la atenci\u00f3n de un p\u00fablico m\u00e1s amplio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Atraer al p\u00fablico objetivo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las publicaciones en los medios de comunicaci\u00f3n pueden atraer la atenci\u00f3n del p\u00fablico objetivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Crear una imagen positiva<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las publicaciones en los medios de comunicaci\u00f3n pueden ayudar a crear una imagen positiva de una marca o evento, especialmente si contienen mensajes sobre el \u00e9xito del evento, la satisfacci\u00f3n de los invitados y la calidad del servicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Atraer socios<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las publicaciones en los medios de comunicaci\u00f3n atraen la atenci\u00f3n de socios y otros profesionales del sector de los eventos, lo que puede conducir a la ampliaci\u00f3n de la red de contactos y a una posible cooperaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Crear autoridad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si una marca o evento es experto en su campo y publica material en los medios de comunicaci\u00f3n, esto puede contribuir a aumentar su autoridad y credibilidad en el sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas verdades son b\u00e1sicas para la agencia RGB IDEA GROUP, por lo que proporcionan a cada uno de sus proyectos una cobertura decente en los medios de comunicaci\u00f3n.<\/p>\n\n\n\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/bBXA93kloy4\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">Problema: los medios se consideran largos, caros y dificultosos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRNEWS.IO:<\/strong> \u00bfQu\u00e9 metas, objetivos o problemas de la empresa resuelven con las publicaciones en los medios de comunicaci\u00f3n?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tatyana B-O:<\/strong> Por supuesto, el reconocimiento, atraer tr\u00e1fico espec\u00edfico y crear reputaci\u00f3n para las marcas, tanto personales como corporativas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRNEWS.IO:<\/strong> \u00bfHan encontrado dificultades a la hora de establecer los procesos de publicaci\u00f3n de sus materiales en los medios de comunicaci\u00f3n y c\u00f3mo les ha ayudado PRNEWS.IO en ello?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tatyana B-O:<\/strong> Para m\u00ed, como gestora de proyectos, siempre es importante trabajar con servicios que puedan describirse con las siguientes palabras:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>claramente<\/li>\n\n\n\n<li>eficazmente<\/li>\n\n\n\n<li>mensurablemente<\/li>\n\n\n\n<li>de forma transparente<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Esta funcionalidad la proporciona PRNEWS.IO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRNEWS.IO:<\/strong> \u00bfHas utilizado antes otras soluciones (servicios) que no funcionaron o no lo hicieron como quer\u00edas?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tatyana B-O:<\/strong> S\u00ed, he tenido varias experiencias trabajando con especialistas en relaciones p\u00fablicas, as\u00ed como comunicaciones personales con publicaciones. <strong>Es largo, caro y conlleva mucho sufrimiento<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En general, encontrar espacios en los medios de comunicaci\u00f3n sobre una marca o un evento es una tarea bastante dif\u00edcil. En la mayor\u00eda de los sectores, hay mucha competencia por el espacio en los medios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que tener en cuenta que se puede perder bastante tiempo en acordar las condiciones de colocaci\u00f3n de materiales con la redacci\u00f3n. Algunos medios pueden cobrarte por publicar tu material, y cuanto mayor sea el perfil del medio, mayor ser\u00e1 el precio por anunciarse y publicar. Adem\u00e1s, no todas las ediciones tienen precio, lo que retrasa considerablemente la comunicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, es importante elegir el lugar adecuado para distribuir los contenidos. Para cada sector, existen medios de nicho especializados en un tema y con un p\u00fablico objetivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Crear una lista de estos sitios especializados puede llevar bastante tiempo. Para estos casos existe el directorio PRNEWS.IO, que contiene una lista de recursos de medios de comunicaci\u00f3n de diversos sectores y regiones, lo que permite encontrar r\u00e1pidamente medios especializados para publicar materiales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/prnews.io\/es\/sites\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"264\" src=\"https:\/\/3.72.156.28\/es\/blog\/wp-content\/uploads\/2023\/04\/6-1024x264.png\" alt=\"\" class=\"wp-image-3045\" srcset=\"\/es\/blog\/wp-content\/uploads\/2023\/04\/6-1024x264.png 1024w, \/es\/blog\/wp-content\/uploads\/2023\/04\/6-300x77.png 300w, \/es\/blog\/wp-content\/uploads\/2023\/04\/6-150x39.png 150w, \/es\/blog\/wp-content\/uploads\/2023\/04\/6-768x198.png 768w, \/es\/blog\/wp-content\/uploads\/2023\/04\/6-1536x396.png 1536w, \/es\/blog\/wp-content\/uploads\/2023\/04\/6-480x124.png 480w, \/es\/blog\/wp-content\/uploads\/2023\/04\/6.png 1940w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Decisi\u00f3n: Haz m\u00e1s de lo que se espera de ti<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRNEWS.IO:<\/strong> \u00bfQu\u00e9 ha hecho el equipo de PRNEWS.IO para lograr sus objetivos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tatyana B-O:<\/strong> En primer lugar, me escuchan. En segundo lugar, trabajamos en equipo. Hay un objetivo, hay una soluci\u00f3n. Adem\u00e1s, tuvimos algunos momentos de trabajo, incluso casos \u00abfallidos\u00bb, pero la forma en que encontramos un compromiso y salimos de la situaci\u00f3n fue muy valiosa. Hacer m\u00e1s de lo que se espera de ti es el principio que nos une.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resultado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRNEWS.IO:<\/strong> \u00bfC\u00f3mo valora los resultados de la cooperaci\u00f3n con PRNEWS.IO?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tatyana B-O:<\/strong> Trabajamos en marcas personales, el reconocimiento y la indexaci\u00f3n en los motores de b\u00fasqueda para consultas clave fue siempre agradable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRNEWS.IO:<\/strong> \u00bfTe dirigir\u00edas al equipo de PRNEWS.IO con un nuevo encargo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tatyana B-O:<\/strong> S\u00ed<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*La indexaci\u00f3n en buscadores significa que un sitio o p\u00e1gina puede aparecer en los resultados de b\u00fasqueda para determinadas consultas que los usuarios introducen en un buscador. Esto impulsa el tr\u00e1fico org\u00e1nico al sitio. Desempe\u00f1a un papel importante a la hora de trabajar en la mejora de la marca, ya que permite atraer la atenci\u00f3n de clientes potenciales sin grandes costes publicitarios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/prnews.io\/get\/personal-publicity\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"264\" src=\"https:\/\/3.72.156.28\/es\/blog\/wp-content\/uploads\/2023\/04\/7-1024x264.png\" alt=\"\" class=\"wp-image-3046\" srcset=\"\/es\/blog\/wp-content\/uploads\/2023\/04\/7-1024x264.png 1024w, \/es\/blog\/wp-content\/uploads\/2023\/04\/7-300x77.png 300w, \/es\/blog\/wp-content\/uploads\/2023\/04\/7-150x39.png 150w, \/es\/blog\/wp-content\/uploads\/2023\/04\/7-768x198.png 768w, \/es\/blog\/wp-content\/uploads\/2023\/04\/7-1536x396.png 1536w, \/es\/blog\/wp-content\/uploads\/2023\/04\/7-480x124.png 480w, \/es\/blog\/wp-content\/uploads\/2023\/04\/7.png 1940w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">En lugar de conclusiones<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PRNEWS.IO:<\/strong> \u00bfQu\u00e9 significa el \u00e9xito para usted?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tatyana B-O:<\/strong> El \u00e9xito es un camino, un movimiento con un equilibrio entre los objetivos y la vida. De lo contrario, podr\u00eda decir que el \u00e9xito es detenerse, congelarse ante la sensaci\u00f3n de victoria y cumplir objetivos. Por lo tanto, considero el \u00e9xito como un movimiento y un deseo de crear algo nuevo, por encima de un techo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Deje volar su imaginaci\u00f3n y nosotros le ayudaremos a dar vida a su creaci\u00f3n.<\/p>\n<cite>PRNEWS.IO<\/cite><\/blockquote>\n\n\n\n<style>\n#PRN-content-platform {\n\tbackground-image: url(\"https:\/\/prnews.io\/blog\/wp-content\/uploads\/2022\/11\/way-to-success.svg\");\n\tbackground-position: right bottom;\n\tbackground-repeat: no-repeat;\n\tbackground-size: 40%;\n}\n#PRN-content-platform-top {\n\tbackground: #f9f9f9;\n\tmargin-top: 10px;\n\tmargin-bottom: 20px;\n\tpadding: 10px 10px 0px 10px;\n\tborder-color: #CCC;\n\tborder-style: solid;\n\tborder-width: 2px;\n}\n#PRN-content-platform-btn\n{\n    font-weight: 400;\n    text-shadow: none;\n    font-family: Lora;\n\n}\n    \n<\/style>\n\n<div style=\"\" id=\"PRN-content-platform-top\"> \n<div id=\"PRN-content-platform\"> <h2>Plataforma de marketing de contenidos<\/h2>\n\n\t<ul style=\"max-width: 62%px;\">\n\t\t<li>M\u00e1s de 100.000 publicaciones en los medios de comunicaci\u00f3n;<\/li>\n\t\t<li>conseguir backlinks hacia su producto;<\/li>\n\t\t<li>trabajo a escala con la distribuci\u00f3n de contenidos.<\/li>\n\t<\/ul>\n    <div class=\"is-layout-flex wp-block-buttons\">\n<div class=\"wp-block-button has-custom-font-size is-style-fill has-medium-font-size\" id=\"PRN-content-platform-btn\"><a href=\"https:\/\/prnews.io\/signup\/\" class=\"wp-block-button__link has-white-color has-text-color has-background wp-element-button\" style=\"border-radius:6px;background-color:#ef3b52;margin-left: 34px;margin-bottom:30px;font-size:14px;line-height: 120%;\" id=\"blog-cta-button\">Inscribirse<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En PRNEWS.IO nos encanta hablar de nuestros clientes y compartir sus historias y logros. Muy a menudo nosotros mismos nos inspiramos en su ejemplo. Hoy hablamos de un cliente tan impresionante. \u00abCreamos marcas, eventos y contenidos con los que se sue\u00f1a y de los que se habla\u00bb. Tetyana Bogoslavska-Orel, cofundadora y directora creativa de la agencia RGB IDEA GROUP. La agencia creativa de marcas y eventos RGB IDEA GROUP es un ejemplo de marca brillante, interesante y, al mismo tiempo, muy concienciada. La agencia tiene ra\u00edces ucranianas, al igual que PRNEWS.IO, y adopta una posici\u00f3n c\u00edvica y de voluntariado muy<\/p>\n","protected":false},"author":2,"featured_media":3048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[851],"tags":[],"class_list":["post-3039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cases"],"aioseo_notices":[],"_links":{"self":[{"href":"\/es\/blog\/wp-json\/wp\/v2\/posts\/3039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"\/es\/blog\/wp-json\/wp\/v2\/comments?post=3039"}],"version-history":[{"count":2,"href":"\/es\/blog\/wp-json\/wp\/v2\/posts\/3039\/revisions"}],"predecessor-version":[{"id":4641,"href":"\/es\/blog\/wp-json\/wp\/v2\/posts\/3039\/revisions\/4641"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/es\/blog\/wp-json\/wp\/v2\/media\/3048"}],"wp:attachment":[{"href":"\/es\/blog\/wp-json\/wp\/v2\/media?parent=3039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/es\/blog\/wp-json\/wp\/v2\/categories?post=3039"},{"taxonomy":"post_tag","embeddable":true,"href":"\/es\/blog\/wp-json\/wp\/v2\/tags?post=3039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}